{"id":612,"count":14,"description":"","link":"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/","name":"Shirts","slug":"shirts","taxonomy":"product_cat","parent":40,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Shirts Arkiv : Eques<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shirts Arkiv : Eques\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/\" \/>\n<meta property=\"og:site_name\" content=\"Eques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/\",\"url\":\"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/\",\"name\":\"Shirts Arkiv : Eques\",\"isPartOf\":{\"@id\":\"https:\/\/eques.dk\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/eques.dk\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shirts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eques.dk\/en\/#website\",\"url\":\"https:\/\/eques.dk\/en\/\",\"name\":\"Eques\",\"description\":\"Rideudstyr til islandske heste i dansk design\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eques.dk\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shirts Arkiv : Eques","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/","og_locale":"en_US","og_type":"article","og_title":"Shirts Arkiv : Eques","og_url":"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/","og_site_name":"Eques","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/","url":"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/","name":"Shirts Arkiv : Eques","isPartOf":{"@id":"https:\/\/eques.dk\/en\/#website"},"breadcrumb":{"@id":"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/eques.dk\/en\/product-category\/for-the-rider\/shirts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/eques.dk\/en\/"},{"@type":"ListItem","position":2,"name":"Shirts"}]},{"@type":"WebSite","@id":"https:\/\/eques.dk\/en\/#website","url":"https:\/\/eques.dk\/en\/","name":"Eques","description":"Rideudstyr til islandske heste i dansk design","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eques.dk\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product_cat\/612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product_cat\/40"}],"wp:post_type":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product?product_cat=612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}