{"id":18135,"date":"2023-11-16T08:28:11","date_gmt":"2023-11-16T08:28:11","guid":{"rendered":"https:\/\/eques.dk\/?post_type=product&#038;p=18135"},"modified":"2026-05-13T08:28:35","modified_gmt":"2026-05-13T08:28:35","slug":"light-winter-gloves-eq80006-bk","status":"publish","type":"product","link":"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/","title":{"rendered":"Light Winter Gloves"},"content":{"rendered":"<p>The gloves are designed in a soft and durable high quality material with a thin but warm Thinsulate\u2122 lining. The gloves are hence warm while still providing a close contact to the reins.<\/p>\n<p>The Velcro closure on the back of the hand ensures a close individual comfort and fit.<\/p>\n<p>The anti-slip effect of the fabric ensures a firm grip on the rein.<\/p>\n<p><strong>Sizes:<\/strong> 6-10.5<\/p>\n<p><strong>Material:<\/strong>Outside: 51% nylon, 49% polyurethane; For: 63% polypropylene, 37% polyester<\/p>\n<p><strong>Washing instructions:<\/strong> Hand wash with mild detergent<\/p>\n<p><strong>Suggested retail price<\/strong>: 36,50 EUR<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lined riding gloves in a soft and durable material.<\/p>\n","protected":false},"featured_media":18319,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[44,40],"product_tag":[],"class_list":{"0":"post-18135","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gloves","7":"product_cat-for-the-rider","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Light Winter Gloves : Eques<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Light Winter Gloves : Eques\" \/>\n<meta property=\"og:description\" content=\"Lined riding gloves in a soft and durable material.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/\" \/>\n<meta property=\"og:site_name\" content=\"Eques\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T08:28:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eques.dk\/wp-content\/uploads\/2023\/11\/EQ80006-BK-20231031-3840.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2047\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/\",\"url\":\"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/\",\"name\":\"Light Winter Gloves : Eques\",\"isPartOf\":{\"@id\":\"https:\/\/eques.dk\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eques.dk\/wp-content\/uploads\/2023\/11\/EQ80006-BK-20231031-3840.jpg\",\"datePublished\":\"2023-11-16T08:28:11+00:00\",\"dateModified\":\"2026-05-13T08:28:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/#primaryimage\",\"url\":\"https:\/\/eques.dk\/wp-content\/uploads\/2023\/11\/EQ80006-BK-20231031-3840.jpg\",\"contentUrl\":\"https:\/\/eques.dk\/wp-content\/uploads\/2023\/11\/EQ80006-BK-20231031-3840.jpg\",\"width\":2048,\"height\":2047},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/eques.dk\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/eques.dk\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Light Winter Gloves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eques.dk\/en\/#website\",\"url\":\"https:\/\/eques.dk\/en\/\",\"name\":\"Eques\",\"description\":\"Rideudstyr til islandske heste i dansk design\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eques.dk\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Light Winter Gloves : Eques","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/","og_locale":"en_US","og_type":"article","og_title":"Light Winter Gloves : Eques","og_description":"Lined riding gloves in a soft and durable material.","og_url":"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/","og_site_name":"Eques","article_modified_time":"2026-05-13T08:28:35+00:00","og_image":[{"width":2048,"height":2047,"url":"https:\/\/eques.dk\/wp-content\/uploads\/2023\/11\/EQ80006-BK-20231031-3840.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/","url":"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/","name":"Light Winter Gloves : Eques","isPartOf":{"@id":"https:\/\/eques.dk\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/#primaryimage"},"image":{"@id":"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/#primaryimage"},"thumbnailUrl":"https:\/\/eques.dk\/wp-content\/uploads\/2023\/11\/EQ80006-BK-20231031-3840.jpg","datePublished":"2023-11-16T08:28:11+00:00","dateModified":"2026-05-13T08:28:35+00:00","breadcrumb":{"@id":"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/#primaryimage","url":"https:\/\/eques.dk\/wp-content\/uploads\/2023\/11\/EQ80006-BK-20231031-3840.jpg","contentUrl":"https:\/\/eques.dk\/wp-content\/uploads\/2023\/11\/EQ80006-BK-20231031-3840.jpg","width":2048,"height":2047},{"@type":"BreadcrumbList","@id":"https:\/\/eques.dk\/en\/product\/light-winter-gloves-eq80006-bk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/eques.dk\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/eques.dk\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Light Winter Gloves"}]},{"@type":"WebSite","@id":"https:\/\/eques.dk\/en\/#website","url":"https:\/\/eques.dk\/en\/","name":"Eques","description":"Rideudstyr til islandske heste i dansk design","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eques.dk\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product\/18135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/media\/18319"}],"wp:attachment":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/media?parent=18135"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product_brand?post=18135"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product_cat?post=18135"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product_tag?post=18135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}