{"id":11907,"date":"2021-06-11T13:28:08","date_gmt":"2021-06-11T14:13:54","guid":{"rendered":"https:\/\/eques.dk\/?post_type=product&#038;p=11907"},"modified":"2023-12-08T08:51:28","modified_gmt":"2023-12-08T08:51:28","slug":"leg-straps-eq71001-5744003873982","status":"publish","type":"product","link":"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/","title":{"rendered":"Leg Straps"},"content":{"rendered":"<p>Separate leg straps that fits the EQUES Fleece Blanket, Wool Blanket and Rain Blanket.<\/p>\n<p>The straps are adjustable in size.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sizes:<\/strong> Onesize<\/p>\n<p><strong>Washing instructions:<\/strong> Mashine wash, gentle program at 30 \u00b0C.<\/p>\n<p><strong>Suggested retail price:<\/strong> 16 EUR<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>(Old SKU: EK-1000)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adjustable leg straps for Fleece Blanket, Wool Blanket and Rain Blanket.<\/p>\n","protected":false},"featured_media":11891,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[321],"product_tag":[],"class_list":{"0":"post-11907","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-blankets","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Leg Straps : Eques<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leg Straps : Eques\" \/>\n<meta property=\"og:description\" content=\"Adjustable leg straps for Fleece Blanket, Wool Blanket and Rain Blanket.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/\" \/>\n<meta property=\"og:site_name\" content=\"Eques\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-08T08:51:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eques.dk\/wp-content\/uploads\/2021\/06\/R5AH7730-Edit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/\",\"url\":\"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/\",\"name\":\"Leg Straps : Eques\",\"isPartOf\":{\"@id\":\"https:\/\/eques.dk\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eques.dk\/wp-content\/uploads\/2021\/06\/R5AH7730-Edit.jpg\",\"datePublished\":\"2021-06-11T14:13:54+00:00\",\"dateModified\":\"2023-12-08T08:51:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/#primaryimage\",\"url\":\"https:\/\/eques.dk\/wp-content\/uploads\/2021\/06\/R5AH7730-Edit.jpg\",\"contentUrl\":\"https:\/\/eques.dk\/wp-content\/uploads\/2021\/06\/R5AH7730-Edit.jpg\",\"width\":2048,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\/\/eques.dk\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/eques.dk\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Leg Straps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eques.dk\/en\/#website\",\"url\":\"https:\/\/eques.dk\/en\/\",\"name\":\"Eques\",\"description\":\"Rideudstyr til islandske heste i dansk design\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eques.dk\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leg Straps : Eques","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/","og_locale":"en_US","og_type":"article","og_title":"Leg Straps : Eques","og_description":"Adjustable leg straps for Fleece Blanket, Wool Blanket and Rain Blanket.","og_url":"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/","og_site_name":"Eques","article_modified_time":"2023-12-08T08:51:28+00:00","og_image":[{"width":2048,"height":2048,"url":"https:\/\/eques.dk\/wp-content\/uploads\/2021\/06\/R5AH7730-Edit.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/","url":"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/","name":"Leg Straps : Eques","isPartOf":{"@id":"https:\/\/eques.dk\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/#primaryimage"},"image":{"@id":"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/#primaryimage"},"thumbnailUrl":"https:\/\/eques.dk\/wp-content\/uploads\/2021\/06\/R5AH7730-Edit.jpg","datePublished":"2021-06-11T14:13:54+00:00","dateModified":"2023-12-08T08:51:28+00:00","breadcrumb":{"@id":"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/#primaryimage","url":"https:\/\/eques.dk\/wp-content\/uploads\/2021\/06\/R5AH7730-Edit.jpg","contentUrl":"https:\/\/eques.dk\/wp-content\/uploads\/2021\/06\/R5AH7730-Edit.jpg","width":2048,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/eques.dk\/en\/product\/leg-straps-eq71001-5744003873982\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/eques.dk\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/eques.dk\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Leg Straps"}]},{"@type":"WebSite","@id":"https:\/\/eques.dk\/en\/#website","url":"https:\/\/eques.dk\/en\/","name":"Eques","description":"Rideudstyr til islandske heste i dansk design","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eques.dk\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product\/11907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/media\/11891"}],"wp:attachment":[{"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/media?parent=11907"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product_brand?post=11907"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product_cat?post=11907"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eques.dk\/en\/wp-json\/wp\/v2\/product_tag?post=11907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}